{"id":3239,"date":"2022-09-30T16:07:30","date_gmt":"2022-09-30T21:07:30","guid":{"rendered":"https:\/\/parquelamexicana.mx\/contacto\/"},"modified":"2022-10-07T12:42:47","modified_gmt":"2022-10-07T17:42:47","slug":"contacto","status":"publish","type":"page","link":"https:\/\/parquelamexicana.tmphost.net\/en\/contacto\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<div class=\"wp-block-group container my-5 is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column border-end pe-2 mb-3 is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"text-center align-self-start text-green wp-block-heading\">Contact<\/h2>\n\n\n\n<div class=\"d-flex flex-column justify-content-center text-center h-100\">\n<p class=\"fs-2 text-green\"><i class=\"fa fa-map-marker fa-fw fa-lg\"><\/i><\/p>\n\n<p>Av. Luis Barrag\u00e1n 505, col. Santa Fe, Alc. Cuajimalpa, C.P. 05348<\/p>\n<p class=\"fs-2 text-green\"><i class=\"fa fa-envelope fa-fw fa-lg\"><\/i><\/p>\n<p>info@parquelamexicana.mx<\/p>\n<p>For matters related to <b>sports fields<\/b>:<\/p> \n<p>canchasdeportivas@parquelamexicana.mx<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"text-center text-green wp-block-heading\">Send us your comments<\/h2>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3283-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/3239#wpcf7-f3283-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3283\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3283-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"form-floating mb-3\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"your-name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<label for=\"your-name\">Full Name*<\/label>\n\t<\/p>\n<\/div>\n<div class=\"form-floating mb-3\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" id=\"your-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<label for=\"your-email\">Email*<\/label>\n\t<\/p>\n<\/div>\n<div class=\"form-floating mb-3\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text form-control\" id=\"your-phone\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><br \/>\n<label for=\"your-phone\">Phone<\/label>\n\t<\/p>\n<\/div>\n<div class=\"form-floating mb-3\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea form-control\" id=\"your-message\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span><br \/>\n<label for=\"your-message\">Message<\/label>\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary w-100\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contact Av. Luis Barrag\u00e1n 505, col. Santa Fe, Alc. Cuajimalpa, C.P. 05348 info@parquelamexicana.mx For matters related to sports fields: canchasdeportivas@parquelamexicana.mx Send us your comments<\/p>\n","protected":false},"author":1,"featured_media":3194,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"contacto.php","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact - Parque La Mexicana<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Parque La Mexicana\" \/>\n<meta property=\"og:description\" content=\"Contact Av. Luis Barrag\u00e1n 505, col. Santa Fe, Alc. Cuajimalpa, C.P. 05348 info@parquelamexicana.mx For matters related to sports fields: canchasdeportivas@parquelamexicana.mx Send us your comments\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parquelamexicana.tmphost.net\/contacto\/\" \/>\n<meta property=\"og:site_name\" content=\"Parque La Mexicana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/parquelamexicanaofcial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-07T17:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg?fit=2000%2C1333&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mexicanaparque\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/\",\"url\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/\",\"name\":\"Contact - Parque La Mexicana\",\"isPartOf\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg\",\"datePublished\":\"2022-09-30T21:07:30+00:00\",\"dateModified\":\"2022-10-07T17:42:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/parquelamexicana.tmphost.net\/contacto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/#primaryimage\",\"url\":\"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg\",\"contentUrl\":\"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/contacto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/parquelamexicana.tmphost.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#website\",\"url\":\"https:\/\/parquelamexicana.tmphost.net\/\",\"name\":\"Parque La Mexicana\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/parquelamexicana.tmphost.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#organization\",\"name\":\"Parque La Mexicana\",\"url\":\"https:\/\/parquelamexicana.tmphost.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1\",\"width\":963,\"height\":255,\"caption\":\"Parque La Mexicana\"},\"image\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/parquelamexicanaofcial\/\",\"https:\/\/twitter.com\/mexicanaparque\",\"https:\/\/www.instagram.com\/parque_la_mexicana_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Parque La Mexicana","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Contact - Parque La Mexicana","og_description":"Contact Av. Luis Barrag\u00e1n 505, col. Santa Fe, Alc. Cuajimalpa, C.P. 05348 info@parquelamexicana.mx For matters related to sports fields: canchasdeportivas@parquelamexicana.mx Send us your comments","og_url":"https:\/\/parquelamexicana.tmphost.net\/contacto\/","og_site_name":"Parque La Mexicana","article_publisher":"https:\/\/www.facebook.com\/parquelamexicanaofcial\/","article_modified_time":"2022-10-07T17:42:47+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg?fit=2000%2C1333&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@mexicanaparque","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/parquelamexicana.tmphost.net\/contacto\/","url":"https:\/\/parquelamexicana.tmphost.net\/contacto\/","name":"Contact - Parque La Mexicana","isPartOf":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parquelamexicana.tmphost.net\/contacto\/#primaryimage"},"image":{"@id":"https:\/\/parquelamexicana.tmphost.net\/contacto\/#primaryimage"},"thumbnailUrl":"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg","datePublished":"2022-09-30T21:07:30+00:00","dateModified":"2022-10-07T17:42:47+00:00","breadcrumb":{"@id":"https:\/\/parquelamexicana.tmphost.net\/contacto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parquelamexicana.tmphost.net\/contacto\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parquelamexicana.tmphost.net\/contacto\/#primaryimage","url":"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg","contentUrl":"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2022\/01\/Parque-La-Mexicana-2.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/parquelamexicana.tmphost.net\/contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/parquelamexicana.tmphost.net\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/parquelamexicana.tmphost.net\/#website","url":"https:\/\/parquelamexicana.tmphost.net\/","name":"Parque La Mexicana","description":"","publisher":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parquelamexicana.tmphost.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/parquelamexicana.tmphost.net\/#organization","name":"Parque La Mexicana","url":"https:\/\/parquelamexicana.tmphost.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1","contentUrl":"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1","width":963,"height":255,"caption":"Parque La Mexicana"},"image":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/parquelamexicanaofcial\/","https:\/\/twitter.com\/mexicanaparque","https:\/\/www.instagram.com\/parque_la_mexicana_\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages\/3239"}],"collection":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/comments?post=3239"}],"version-history":[{"count":5,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages\/3239\/revisions"}],"predecessor-version":[{"id":3287,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages\/3239\/revisions\/3287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/media\/3194"}],"wp:attachment":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/media?parent=3239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}