{"id":3242,"date":"2022-10-03T09:26:27","date_gmt":"2022-10-03T14:26:27","guid":{"rendered":"https:\/\/parquelamexicana.mx\/la-mexicana-park\/"},"modified":"2022-10-05T10:46:16","modified_gmt":"2022-10-05T15:46:16","slug":"la-mexicana-park","status":"publish","type":"page","link":"https:\/\/parquelamexicana.tmphost.net\/en\/","title":{"rendered":"La Mexicana Park"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3142,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Mexicana Park in Santa Fe, CDMX | Directions, Park rules and more<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Mexicana Park in Santa Fe, CDMX | Directions, Park rules and more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parquelamexicana.tmphost.net\/\" \/>\n<meta property=\"og:site_name\" content=\"Parque La Mexicana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/parquelamexicanaofcial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T15:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg?fit=2048%2C1280&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mexicanaparque\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/\",\"url\":\"https:\/\/parquelamexicana.tmphost.net\/\",\"name\":\"La Mexicana Park in Santa Fe, CDMX | Directions, Park rules and more\",\"isPartOf\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg\",\"datePublished\":\"2022-10-03T14:26:27+00:00\",\"dateModified\":\"2022-10-05T15:46:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/parquelamexicana.tmphost.net\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#primaryimage\",\"url\":\"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg\",\"contentUrl\":\"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg\",\"width\":2048,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/parquelamexicana.tmphost.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Mexicana Park\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#website\",\"url\":\"https:\/\/parquelamexicana.tmphost.net\/\",\"name\":\"Parque La Mexicana\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/parquelamexicana.tmphost.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#organization\",\"name\":\"Parque La Mexicana\",\"url\":\"https:\/\/parquelamexicana.tmphost.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1\",\"width\":963,\"height\":255,\"caption\":\"Parque La Mexicana\"},\"image\":{\"@id\":\"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/parquelamexicanaofcial\/\",\"https:\/\/twitter.com\/mexicanaparque\",\"https:\/\/www.instagram.com\/parque_la_mexicana_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Mexicana Park in Santa Fe, CDMX | Directions, Park rules and more","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"La Mexicana Park in Santa Fe, CDMX | Directions, Park rules and more","og_url":"https:\/\/parquelamexicana.tmphost.net\/","og_site_name":"Parque La Mexicana","article_publisher":"https:\/\/www.facebook.com\/parquelamexicanaofcial\/","article_modified_time":"2022-10-05T15:46:16+00:00","og_image":[{"width":2048,"height":1280,"url":"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg?fit=2048%2C1280&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@mexicanaparque","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/parquelamexicana.tmphost.net\/","url":"https:\/\/parquelamexicana.tmphost.net\/","name":"La Mexicana Park in Santa Fe, CDMX | Directions, Park rules and more","isPartOf":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#primaryimage"},"image":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#primaryimage"},"thumbnailUrl":"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg","datePublished":"2022-10-03T14:26:27+00:00","dateModified":"2022-10-05T15:46:16+00:00","breadcrumb":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parquelamexicana.tmphost.net\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parquelamexicana.tmphost.net\/#primaryimage","url":"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg","contentUrl":"https:\/\/parquelamexicana.mx\/wp-content\/uploads\/2021\/12\/hero-img.jpg","width":2048,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/parquelamexicana.tmphost.net\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/parquelamexicana.tmphost.net\/"},{"@type":"ListItem","position":2,"name":"La Mexicana Park"}]},{"@type":"WebSite","@id":"https:\/\/parquelamexicana.tmphost.net\/#website","url":"https:\/\/parquelamexicana.tmphost.net\/","name":"Parque La Mexicana","description":"","publisher":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parquelamexicana.tmphost.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/parquelamexicana.tmphost.net\/#organization","name":"Parque La Mexicana","url":"https:\/\/parquelamexicana.tmphost.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1","contentUrl":"https:\/\/i0.wp.com\/parquelamexicana.mx\/wp-content\/uploads\/2019\/04\/la-mexicana-logo-final.png?fit=963%2C255&ssl=1","width":963,"height":255,"caption":"Parque La Mexicana"},"image":{"@id":"https:\/\/parquelamexicana.tmphost.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/parquelamexicanaofcial\/","https:\/\/twitter.com\/mexicanaparque","https:\/\/www.instagram.com\/parque_la_mexicana_\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages\/3242"}],"collection":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/comments?post=3242"}],"version-history":[{"count":2,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages\/3242\/revisions"}],"predecessor-version":[{"id":3281,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/pages\/3242\/revisions\/3281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/media\/3142"}],"wp:attachment":[{"href":"https:\/\/parquelamexicana.tmphost.net\/en\/wp-json\/wp\/v2\/media?parent=3242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}